{"id":74357,"date":"2020-04-27T12:11:48","date_gmt":"2020-04-27T11:11:48","guid":{"rendered":"https:\/\/www.conasi.eu\/blog\/?p=74357"},"modified":"2022-09-27T07:15:29","modified_gmt":"2022-09-27T06:15:29","slug":"pan-casero-masa-madre-trucos-consejos","status":"publish","type":"post","link":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/","title":{"rendered":"Pan casero con masa madre: trucos y consejos"},"content":{"rendered":"<figure id=\"attachment_74392\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74392 size-large\" title=\"Pan masa madre redondo sobre un pa\u00f1o\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-900x563.jpg\" alt=\"Pan masa madre redondo sobre un pa\u00f1o\" width=\"900\" height=\"563\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-900x563.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-500x313.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-768x480.jpg 768w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-400x250.jpg 400w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-550x345.jpg 550w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg 1200w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">Trucos y dudas m\u00e1s habituales sobre c\u00f3mo hacer pan con masa madre.<\/figcaption><\/figure>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_80 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice del art\u00edculo<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a570b59f1a65\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a570b59f1a65\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Pan_casero_con_masa_madre_y_sus_ventajas\" >Pan casero con masa madre y sus ventajas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_harina_para_la_masa_madre_y_la_masa_madre_para_el_pan\" >La harina para la masa madre y la masa madre para el pan<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Aspectos_a_tener_en_cuenta\" >Aspectos a tener en cuenta<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Conversion_de_la_harina\" >Conversi\u00f3n de la harina<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFSe_puede_usar_la_masa_madre_para_otras_preparaciones_que_no_sean_pan\" >\u00bfSe puede usar la masa madre para otras preparaciones que no sean pan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_temperatura\" >La temperatura<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Climas_frios\" >Climas fr\u00edos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Climas_calidos\" >Climas c\u00e1lidos<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#El_agua\" >El agua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFPor_que_remover_la_masa_madre\" >\u00bfPor qu\u00e9 remover la masa madre?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFPor_que_desechamos_una_parte_de_la_masa_madre\" >\u00bfPor qu\u00e9 desechamos una parte de la masa madre?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFQue_cantidad_descartar\" >\u00bfQu\u00e9 cantidad descartar?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFQue_podemos_hacer_con_la_masa_madre_que_descartamos\" >\u00bfQu\u00e9 podemos hacer con la masa madre qu\u00e9 descartamos?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Porcentaje_de_hidratacion_de_la_masa_madre\" >Porcentaje de hidrataci\u00f3n de la masa madre<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Masa_madre_mas_liquida\" >Masa madre m\u00e1s l\u00edquida<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Masa_madre_mas_solida\" >Masa madre m\u00e1s s\u00f3lida<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_masa_madre_vigorosa_el_punto_mas_importante_a_la_hora_de_hacer_pan_casero_con_masa_madre\" >La masa madre vigorosa: el punto m\u00e1s importante a la hora de hacer pan casero con masa madre<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFComo_saber_que_la_masa_madre_esta_en_su_punto_optimo_para_elaborar_el_pan\" >\u00bfC\u00f3mo saber que la masa madre est\u00e1 en su punto \u00f3ptimo para elaborar el pan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFQue_ocurre_si_no_se_alimenta_con_regularidad_la_masa_madre\" >\u00bfQu\u00e9 ocurre si no se alimenta con regularidad la masa madre?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#A_la_hora_de_elaborar_el_pan_casero_con_masa_madre\" >A la hora de elaborar el pan casero con masa madre<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFComo_preparar_la_masa_madre_antes_de_elaborar_pan\" >\u00bfC\u00f3mo preparar la masa madre antes de elaborar pan?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFCuanta_masa_madre_utilizo_para_elaborar_un_pan_casero\" >\u00bfCu\u00e1nta masa madre utilizo para elaborar un pan casero?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFCuanta_agua_utilizo_para_elaborar_un_pan_El_porcentaje_de_hidratacion\" >\u00bfCu\u00e1nta agua utilizo para elaborar un pan? El porcentaje de hidrataci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_autolisis\" >La autolisis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_humedad_de_la_masa\" >La humedad de la masa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#%C2%BFComo_saber_el_punto_correcto_de_amasado_de_la_masa\" >\u00bfC\u00f3mo saber el punto correcto de amasado de la masa?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Caracteristicas_de_una_masa_bien_amasada\" >Caracter\u00edsticas de una masa bien amasada<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#La_fermentacion_de_la_masa\" >La fermentaci\u00f3n de la masa<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#El_punto_correcto_de_horneado\" >El punto correcto de horneado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#Indicadores_de_que_la_masa_no_esta_en_el_punto_correcto\" >Indicadores de que la masa no est\u00e1 en el punto correcto<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Pan_casero_con_masa_madre_y_sus_ventajas\"><\/span>Pan casero con masa madre y sus ventajas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\"><strong>\u00a1El pan casero con masa madre ha vuelto para quedarse!<\/strong> Cada vez son m\u00e1s las personas que deciden <a title=\"Recetas de panes y masas de panader\u00eda\" href=\"https:\/\/www.conasi.eu\/blog\/secciones\/recetas\/panes-y-masas-de-panaderia\/\">hacer su propio pan en casa<\/a> de la forma m\u00e1s primigenia y digestiva: con <strong><a title=\"Harinas ecol\u00f3gicas y biodin\u00e1micas\" href=\"https:\/\/www.conasi.eu\/25-harinas\">harinas de calidad<\/a>,\u00a0 fermentaciones largas y con levaduras y bacterias naturales, salvajes y locales<\/strong>. \u00a1Prescinde de comprar levaduras, si consigues una buena masa madre!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el <a title=\"Todo sobre la masa madre\" href=\"https:\/\/www.conasi.eu\/blog\/consejos-de-salud\/tutorial-como-elaborar-la-levadura-madre\/\">tutorial para hacer masa madre<\/a> ya os cont\u00e1bamos qu\u00e9 es y los pasos b\u00e1sicos a seguir para elaborarla <\/span><span style=\"font-weight: 400;\">y en la <\/span><a title=\"Receta de pan de masa madre\" href=\"https:\/\/www.conasi.eu\/blog\/recetas\/pan-de-masa-madre\/\"><span style=\"font-weight: 400;\">receta de pan de masa madre<\/span><\/a><span style=\"font-weight: 400;\"> se puede ver un ejemplo de c\u00f3mo hacer el pan casero con masa madre, tanto a mano como con panificadora.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este art\u00edculo vamos a tratar de <\/span><b>resolver las dudas m\u00e1s habituales <\/b><span style=\"font-weight: 400;\">que hemos ido recogiendo a lo largo de estos a\u00f1os en referencia a la masa madre y al pan fermentado de forma natural. Tambi\u00e9n vamos a explicar algunos <\/span><b>consejos que nos han resultado de gran utilidad.<\/b><\/p>\n<p><b>Entre las ventajas de la elaboraci\u00f3n de pan casero con masa madre destacamos las siguientes:<\/b><\/p>\n<ul>\n<li><b>El sabor:<\/b><span style=\"font-weight: 400;\"> mayor profundidad de sabor.<\/span><\/li>\n<li><b>La conservaci\u00f3n:<\/b><span style=\"font-weight: 400;\"> los panes de masa madre envejecen mejor, conservan m\u00e1s su humedad y mejoran con el tiempo, debido a que la acidez de la masa protege el pan de la aparici\u00f3n de mohos y bacterias.<\/span><\/li>\n<li><b>La digesti\u00f3n y asimilaci\u00f3n<\/b><span style=\"font-weight: 400;\">: con fermentaciones naturales y largas se predigiere al m\u00e1ximo el cereal, aumentando la biodisponibilidad de sus nutrientes.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"La_harina_para_la_masa_madre_y_la_masa_madre_para_el_pan\"><\/span>La harina para la masa madre y la masa madre para el pan<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">Se puede usar <\/span><b>cualquier tipo de harina para hacer masa madre, <\/b><span style=\"font-weight: 400;\">pero si es de buena calidad dar\u00e1 un mejor resultado.<\/span><\/li>\n<li><b>Las harinas integrales<\/b> <b>consiguen un mayor crecimiento<\/b><span style=\"font-weight: 400;\"> de la masa madre debido a su mayor contenido en microorganismos y nutrientes.<\/span><\/li>\n<li><b>Las harinas con mayor fuerza<\/b><span style=\"font-weight: 400;\"> consiguen una masa madre con m\u00e1s vigor y actividad durante m\u00e1s tiempo.<\/span><\/li>\n<li><b>Las <a title=\"Molinos el\u00e9ctricos para harina\" href=\"https:\/\/www.conasi.eu\/blog\/productos\/elegir-el-molino-mas-adecuado\/\">harinas reci\u00e9n molidas<\/a><\/b><span style=\"font-weight: 400;\"> tienden a necesitar un reposo de unos d\u00edas para desarrollar una mayor actividad microbiana.<\/span><\/li>\n<li><b>La <a title=\"Harina de centeno semiintegral ecol\u00f3gica\" href=\"https:\/\/www.conasi.eu\/harinas\/308-harina-centeno-semiintegral.html\">harina de centeno<\/a><\/b> <b>fermenta m\u00e1s r\u00e1pidamente<\/b><span style=\"font-weight: 400;\"> y da muy buen resultado para comenzar la fermentaci\u00f3n, asimismo aporta un sabor m\u00e1s pronunciado al pan.<\/span><\/li>\n<li><b>Las <a title=\"Harina de trigo blanca ecol\u00f3gica y biodin\u00e1mica\" href=\"https:\/\/www.conasi.eu\/harinas\/164-harina-de-fuerza.html\">harinas blancas<\/a><\/b><span style=\"font-weight: 400;\"> permiten que la masa madre fermente m\u00e1s lentamente y por lo tanto, evitan que la tengamos que alimentar tan a menudo, lo cual en ocasiones puede resultar una gran ventaja.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Se puede hacer pan casero con masa madre con un tipo de harina diferente a la que hemos usado en el fermento, dicho de otra manera, no es estrictamente necesario utilizar una masa madre diferente para cada tipo de pan. A nivel casero y sin grandes ambiciones panaderas, <\/span><b>podemos tener una sola masa madre para todos los panes que hacemos habitualmente.<\/b><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Aspectos_a_tener_en_cuenta\"><\/span>Aspectos a tener en cuenta<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Cada tipo de masa madre<\/b><span style=\"font-weight: 400;\">, seg\u00fan la harina que la alimenta y sobre todo, seg\u00fan el entorno microbiol\u00f3gico del lugar d\u00f3nde la elaboramos, <\/span><b>act\u00faa diferente en lo que respecta al sabor, la velocidad de fermentaci\u00f3n y el resultado final del pan.<\/b><\/li>\n<li><b>Lo que hace \u00fanica a un tipo de masa madre<\/b><span style=\"font-weight: 400;\"> es por un lado, el tipo de harina con la que se cultiva, pero <\/span><b>sobre todo, las diferentes levaduras silvestres del lugar donde se ha fermentado.<\/b><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Conversion_de_la_harina\"><\/span>Conversi\u00f3n de la harina<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Usar el mismo tipo de harina que empleamos en la masa madre que la harina que vamos a emplear en la elaboraci\u00f3n del pan influenciar\u00e1 en la uniformidad del sabor y las caracter\u00edsticas del pan. Pero insistimos, <\/span><b>no es imprescindible.<\/b><\/li>\n<li><b>Podemos convertir una masa madre de una harina determinada a una masa madre de otra harina<\/b><span style=\"font-weight: 400;\">:<\/span>\n<ul>\n<li><span style=\"font-weight: 400;\">Lo que haremos <\/span><b>es refrescar la masa madre<\/b><span style=\"font-weight: 400;\"> durante varios d\u00edas o tandas (pueden ser tandas de entre 4 a 24 horas) con la harina que vamos a usar a posteriori para hacer el pan.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La masa madre, en este caso, <\/span><b>pasar\u00e1 por un per\u00edodo de ajuste <\/b><span style=\"font-weight: 400;\">en el que no estar\u00e1 tan vigorosa y deber\u00e1 adaptarse a las condiciones de la nueva harina.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Por ejemplo, si queremos <\/span><b>pasar de hacer un pan integral a un pan blanco <\/b><span style=\"font-weight: 400;\">y tenemos una masa madre alimentada con harina integral, podemos realizar unos cuantos refrescos de la masa madre con harina blanca, hasta que \u00e9sta vuelva a coger el punto \u00f3ptimo para hacer pan.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si vamos a modificar la masa madre con otro tipo de harina, es recomendable <\/span><b>guardar 1\/2 taza de la masa madre original,<\/b><span style=\"font-weight: 400;\"> ya que no sabemos c\u00f3mo va a reaccionar con el cambio.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFSe_puede_usar_la_masa_madre_para_otras_preparaciones_que_no_sean_pan\"><\/span>\u00bfSe puede usar la masa madre para otras preparaciones que no sean pan?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">La masa madre se puede usar, adem\u00e1s de usarla para hacer pan, para otras recetas como <\/span><b>la masa de pizza, galletas, pancakes, crackers, bizcochos, gofres,<\/b><span style=\"font-weight: 400;\"> etc. Tambi\u00e9n en otras culturas la utilizan para la elaboraci\u00f3n de sopas, bebidas como el kvass y cremas o gachas de cereales.<\/span><\/p>\n<figure id=\"attachment_74385\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74385 size-large\" title=\"Agua y harina en un bol - Pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-1-900x600.jpg\" alt=\"Agua y harina en un bol - Pan casero con masa madre\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-1.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-1-500x333.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">Dependiendo de la temperatural lugar donde vivas, habr\u00e1 que utilizar el agua a una u otra temperatura.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"La_temperatura\"><\/span>La temperatura<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Mantener la masa madre a una temperatura constante de entre <\/span><b>20 a 30\u00baC y sin corrientes de aire<\/b><span style=\"font-weight: 400;\">\u00a0ser\u00e1 una forma de asegurarnos la estabilidad necesaria, es un punto clave. Entre 26 y 30\u00baC es la temperatura ideal de crecimiento, pero a menor temperatura tambi\u00e9n se desarrollar\u00e1, aunque m\u00e1s despacio.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Climas_frios\"><\/span>Climas fr\u00edos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">En invierno, si tenemos una temperatura baja en la cocina<\/span><b>, usar agua ligeramente tibia a unos 24 \u00baC<\/b><span style=\"font-weight: 400;\"> para alimentar la masa madre y para elaborar el pan, ser\u00e1 de gran ayuda para propiciar la fermentaci\u00f3n.<\/span><\/li>\n<li><b>Para mantener una temperatura c\u00e1lida a la hora de fermentar el pan casero con masa madre<\/b><span style=\"font-weight: 400;\"> hay varios trucos, pero hay que tener en cuenta que de esta forma, fermentar\u00e1 mucho m\u00e1s r\u00e1pido:<\/span>\n<ul>\n<li><span style=\"font-weight: 400;\">Usar una bolsa t\u00e9rmica, como <\/span><a title=\"Sistema de retenci\u00f3n de calor tradicional\" href=\"https:\/\/www.conasi.eu\/cocina-lenta\/1646-wonderbag-mediano-hojas-azules.html\"><span style=\"font-weight: 400;\">Wonderbag<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Usar el horno precalentado ligeramente a menos de 50 \u00baC (apagar el horno un rato antes de introducir la masa).\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Mantener la luz del horno encendida tambi\u00e9n proporcionar\u00e1 una temperatura adecuada para la fermentaci\u00f3n.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Usar <\/span><b>una <\/b><a title=\"Fermentadora Brod&amp;Taylor\" href=\"https:\/\/www.conasi.eu\/fermentadoras\/1626-fermentadora-slow-cooker-brod-taylor.html\"><b>fermentadora<\/b><\/a><span style=\"font-weight: 400;\"> para mantener una temperatura constante y controlada de fermentaci\u00f3n.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Climas_calidos\"><\/span>Climas c\u00e1lidos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">En verano, con temperaturas m\u00e1s elevadas, <\/span><b>convendr\u00e1 usar agua fresca para alimentar la masa madre<\/b><span style=\"font-weight: 400;\">, ponerla en los lugares menos c\u00e1lidos de la cocina. Incluso si fermenta muy r\u00e1pido, se recomienda utilizar agua fr\u00eda de la nevera para refrescar la masa madre y para elaborar la masa del pan.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Ser\u00e1 beneficioso <\/span><b>remover m\u00e1s a menudo la masa madre para favorecer la propagaci\u00f3n de bacterias beneficiosas.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Si la masa fermenta muy <\/span><b>r\u00e1pido, ser\u00e1 conveniente alimentarla m\u00e1s a menudo.<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Tambi\u00e9n podremos ponerla <\/span><b>en la parte m\u00e1s c\u00e1lida de la nevera<\/b><span style=\"font-weight: 400;\">. Seguir\u00e1 fermentando, pero con menor riesgo de que se estropee. La sacaremos entre 1-3 d\u00edas antes de la preparaci\u00f3n del pan para refrescarla varias veces y que vuelva a activarse. Si la conservamos en la nevera convendr\u00e1 alimentarla como m\u00ednimo 1 vez por semana.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"El_agua\"><\/span>El agua<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">La calidad del agua importa para alimentar la masa madre y para elaborar el pan.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">El agua filtrada y libre de impurezas influenciar\u00e1 favorablemente en la calidad, vitalidad del fermento y en el sabor del pan.\u00a0<\/span><\/li>\n<li><b>El agua del grifo generalmente contiene cloraminas, cloro y fluoruro,<\/b><span style=\"font-weight: 400;\"> que deben eliminarse para mantener la masa madre o cualquier fermento y producir una buena fermentaci\u00f3n.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">En Conasi adem\u00e1s <\/span><a title=\"Utensilios vitalizadores de Nature's Design\" href=\"https:\/\/www.conasi.eu\/262-vitalizacion\"><b>vitalizamos el agua<\/b><\/a><span style=\"font-weight: 400;\"> que vamos a utilizar para elaborar cualquier tipo de fermento, y os aseguramos que notamos diferencias en el aspecto y vigor de \u00e9stos.<\/span><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_remover_la_masa_madre\"><\/span>\u00bfPor qu\u00e9 remover la masa madre?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">Oxigena el fermento.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Impide el desarrollo de mohos.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Estimula la actividad microbiana.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_74398\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74398 size-large\" title=\"Jarra de vitalizaci\u00f3n del agua Nature's Design - Pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-12-1-900x600.jpg\" alt=\"Jarra de vitalizaci\u00f3n del agua Nature's Design - Pan casero con masa madre\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-12-1.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-12-1-500x333.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-12-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">El agua vitalizada le proporciona al pan unas caracter\u00edsticas destacadas.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_desechamos_una_parte_de_la_masa_madre\"><\/span>\u00bfPor qu\u00e9 desechamos una parte de la masa madre?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>No es un paso imprescindible<\/b><span style=\"font-weight: 400;\"> y recomendamos comenzar a practicarlo a partir del tercer o cuarto d\u00eda de elaboraci\u00f3n de la masa madre.\u00a0<\/span><span style=\"font-weight: 400;\">Beneficios:<\/span><\/p>\n<ul>\n<li><b>Impulsa a la masa madre y aumenta la velocidad y el vigor de la fermentaci\u00f3n.<\/b><\/li>\n<li><b>Disminuye la acidez,<\/b><span style=\"font-weight: 400;\"> ayudando a equilibrarla.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Se obtiene un <\/span><b>pan m\u00e1s ligero<\/b><span style=\"font-weight: 400;\"> y m\u00e1s matices de sabor.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si no descart\u00e1semos una parte, se acumular\u00eda mucha masa madre y esta requerir\u00eda demasiada harina para alimentarla.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQue_cantidad_descartar\"><\/span>\u00bfQu\u00e9 cantidad descartar?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Entre un <\/span><b>50-75%<\/b><span style=\"font-weight: 400;\"> de la masa madre.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQue_podemos_hacer_con_la_masa_madre_que_descartamos\"><\/span>\u00bfQu\u00e9 podemos hacer con la masa madre qu\u00e9 descartamos?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Se le pueden dar muchos usos a la masa madre, pero nos parece especialmente interesante usarla para<\/span> <b>a\u00f1adir al compost directamente<\/b><span style=\"font-weight: 400;\">, aport\u00e1ndole mayor impulso y actividad.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Tambi\u00e9n se puede <strong>a\u00f1adir en m\u00faltiples recetas<\/strong> como por ejemplo, en tortitas para asar en la sart\u00e9n o cualquier receta que vayamos a hornear. Sandor Ellitz nos explica su famosa receta de tortitas saladas de masa madre en su libro \u201c<\/span><a href=\"https:\/\/www.conasi.eu\/varios\/1568-libro-el-arte-de-la-fermentacion-sandor-ellix-katz.html\"><span style=\"font-weight: 400;\">El arte de la fermentaci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\">\u201d.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_74393\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74393 size-large\" title=\"Compostadora casera - pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-9-1-900x600.jpg\" alt=\"Compostadora casera - pan casero con masa madre\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-9-1.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-9-1-500x333.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-9-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">A\u00f1ade masa madre al compost para enriquecer la microbiota.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"Porcentaje_de_hidratacion_de_la_masa_madre\"><\/span>Porcentaje de hidrataci\u00f3n de la masa madre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Podemos hacer una <\/span><b>masa madre con mayor o menor contenido de agua<\/b><span style=\"font-weight: 400;\"> en relaci\u00f3n a la masa madre y a la harina que vamos a utilizar para refrescarla.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Masa_madre_mas_liquida\"><\/span>Masa madre m\u00e1s l\u00edquida<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Tiene un porcentaje mayor de hidrataci\u00f3n, es decir<\/span><b>, se le a\u00f1ade igual o m\u00e1s cantidad de agua que de harina<\/b><span style=\"font-weight: 400;\">, respecto a la cantidad de masa madre.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Una masa madre l\u00edquida <\/span><b>fermenta m\u00e1s r\u00e1pido y desarrolla m\u00e1s \u00e1cido l\u00e1ctico<\/b><span style=\"font-weight: 400;\">. \u00c9ste procura <\/span><b>un sabor m\u00e1s suave y m\u00e1s volumen al pan y favorece una mayor esponjosidad,<\/b><span style=\"font-weight: 400;\"> pero fermenta m\u00e1s r\u00e1pido. Por esa raz\u00f3n hay que alimentarla m\u00e1s a menudo.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Por otro lado, la masa madre m\u00e1s hidratada es m\u00e1s f\u00e1cil y pr\u00e1ctica de refrescar, ya que se puede remover dentro del mismo tarro con una cuchara, sin necesidad de amasar con las manos.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Masa_madre_mas_solida\"><\/span>Masa madre m\u00e1s s\u00f3lida<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Tiene un porcentaje de hidrataci\u00f3n menor, es decir<\/span><b>, se a\u00f1ade menor cantidad de agua que de harina<\/b><span style=\"font-weight: 400;\">, respecto a la cantidad de masa madre.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Una masa madre m\u00e1s s\u00f3lida tiene una <\/span><b>menor actividad fermentativa<\/b><span style=\"font-weight: 400;\"> y una mayor acidez en el sabor. Asimismo tiene tendencia a desarrollar m\u00e1s \u00e1cido ac\u00e9tico, con lo cual <\/span><b>se puede mantener m\u00e1s tiempo sin alimentar o remover con menor peligro de que se pase.\u00a0<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Es m\u00e1s f\u00e1cil de transportar.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Es necesario amasarla con las manos cuando realizamos el refresco.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Para <\/span><b>panes elaborados con harinas sin gluten, suele funcionar mejor la masa madre con menor porcentaje de hidrataci\u00f3n,<\/b><span style=\"font-weight: 400;\"> es decir, m\u00e1s s\u00f3lida. Aguanta mejor el amasado y le aporta m\u00e1s fuerza de cohesi\u00f3n. Y os ofrecemos toda la informaci\u00f3n si quer\u00e9is elaborar <a title=\"Hacer masa madre sin gluten\" href=\"https:\/\/www.conasi.eu\/blog\/consejos-de-salud\/beneficios-fermentar-masa-madre\/\">masas madre sin gluten<\/a>, <a title=\"Panes y bizcochos de y con madre sin gluten\" href=\"https:\/\/www.conasi.eu\/blog\/recetas\/celiacos\/receta-de-pan-sin-gluten\/\">panes y bizcochos sin gluten, con masa madre sin gluten<\/a>.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_66019\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-66019 size-large\" title=\"Masa madre en un tarro de cristal - Pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11-900x563.jpg\" alt=\"Masa madre en un tarro de cristal - Pan casero con masa madre\" width=\"900\" height=\"563\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11-900x563.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11-500x313.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11-400x250.jpg 400w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11-550x345.jpg 550w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2019\/09\/masa-madre-11.jpg 1200w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">El olor y las burbujas nos indican si la masa madre est\u00e1 bien fermentada.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"La_masa_madre_vigorosa_el_punto_mas_importante_a_la_hora_de_hacer_pan_casero_con_masa_madre\"><\/span>La masa madre vigorosa: el punto m\u00e1s importante a la hora de hacer pan casero con masa madre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><span style=\"font-weight: 400;\">Una de las grandes claves del \u00e9xito a la hora de hacer pan casero con masa madre, <\/span><b>es usar la masa madre solamente cuando est\u00e9 completamente activa<\/b><span style=\"font-weight: 400;\"> y preparada para preparar el pan. Ello requiere paciencia, pr\u00e1ctica y experiencia.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Cuando las levaduras y las bacterias est\u00e1n en su punto \u00f3ptimo de actividad<\/span><b>, las podremos usar como levadura natural para el pan<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si la masa madre no est\u00e1 lo suficientemente activa y lista para la acci\u00f3n, el pan nos quedar\u00e1 \u201ca medias tintas\u201d, es decir, no levar\u00e1 o levar\u00e1 poco, quedar\u00e1 demasiado compacto, con menos agujeros y se secar\u00e1 m\u00e1s r\u00e1pidamente.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFComo_saber_que_la_masa_madre_esta_en_su_punto_optimo_para_elaborar_el_pan\"><\/span>\u00bfC\u00f3mo saber que la masa madre est\u00e1 en su punto \u00f3ptimo para elaborar el pan?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Crece, burbujea, huele bien, est\u00e1 esponjosa<\/b><span style=\"font-weight: 400;\">, parece que va a salir sola del tarro.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Se alimenta la masa madre durante tres veces seguidas y se observa que la masa est\u00e1 muy activa, crece y burbujea.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si se alimenta la masa madre y <\/span><b>en un periodo de unas 4\/6 horas aumenta notablemente de volumen<\/b><span style=\"font-weight: 400;\">, \u00a1esa<\/span> <span style=\"font-weight: 400;\">es una se\u00f1al indiscutible de que est\u00e1 lista para trabajar!<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Tener en cuenta que <\/span><b>si la masa madre es muy l\u00edquida,<\/b><span style=\"font-weight: 400;\"> no aumentar\u00e1 tanto de volumen como si es m\u00e1s densa.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Cuando est\u00e1 en su punto \u00e1lgido de actividad no ser\u00e1 tan necesario descartar una parte de la masa madre para alimentarla, ya que ya tiene la fuerza suficiente para crecer.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Otra forma de comprobar que est\u00e1 en su punto <\/span><b>es la prueba de la flotabilidad. <\/b><span style=\"font-weight: 400;\">Esta prueba nos asegura que tiene buen aire y estructura: al poner una cucharada de masa madre en un cuenco de agua la masa debe flotar.\u00a0<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQue_ocurre_si_no_se_alimenta_con_regularidad_la_masa_madre\"><\/span>\u00bfQu\u00e9 ocurre si no se alimenta con regularidad la masa madre?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Depender\u00e1 <\/span><b>de la temperatura del lugar donde se encuentre<\/b><span style=\"font-weight: 400;\"> y del ritmo de crecimiento que tenga.\u00a0<\/span><\/li>\n<li><b>Generalmente no pasar\u00e1 nada grave si nos descuidamos unos d\u00edas<\/b><span style=\"font-weight: 400;\"> y no hace mucho calor, no\u00a0<\/span><span style=\"font-weight: 400;\">ocurrir\u00e1 nada insalvable. La volveremos a alimentar con regularidad y pronto volver\u00e1 a coger ritmo y vigor.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Pero si nos despistamos en verano o durante demasiado tiempo, la masa se acidificar\u00e1 demasiado, comenzar\u00e1n a desarrollarse microorganismos nocivos e incluso puede llegar a aparecer moho y podredumbre. En tal caso es mejor desecharla y volver a comenzar.\u00a0<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_74388\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74388 size-large\" title=\"Masa de pan sobre una mesa de madera - Pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-3-1-900x600.jpg\" alt=\"Masa de pan sobre una mesa de madera - Pan casero con masa madre\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-3-1.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-3-1-500x333.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-3-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">Antes de hacer pan ten en cuenta refrescar la masa madre unos d\u00edas antes.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"A_la_hora_de_elaborar_el_pan_casero_con_masa_madre\"><\/span>A la hora de elaborar el pan casero con masa madre<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Hay muchas maneras y t\u00e9cnicas diferentes de elaborar pan de masa madre, pero queremos exponer unos consejos sencillos:<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFComo_preparar_la_masa_madre_antes_de_elaborar_pan\"><\/span>\u00bfC\u00f3mo preparar la masa madre antes de elaborar pan?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Si tenemos pensado elaborar pan, recomendamos refrescar la masa madre un par o tres de d\u00edas antes. La refrescaremos una vez al d\u00eda y con una proporci\u00f3n alta de harina y agua respecto a la cantidad de masa madre. Con ello, <\/span><b>disminuiremos la acidez y conseguiremos un levado m\u00e1s r\u00e1pido, con lo que obtendremos un pan con un sabor m\u00e1s suave.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Si la refrescamos dos veces al d\u00eda o a intervalos m\u00e1s cortos, <\/span><b>aumentaremos la velocidad de fermentaci\u00f3n<\/b><span style=\"font-weight: 400;\">. Si tenemos prisa, es una ventaja.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Refrescaremos, por lo tanto, la masa dos o tres veces teniendo en cuenta:\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a01-Desechar entre un 50-90% de la masa madre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a02-Alimentar con una proporci\u00f3n de harina y agua similar al volumen que hemos desechado.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFCuanta_masa_madre_utilizo_para_elaborar_un_pan_casero\"><\/span>\u00bfCu\u00e1nta masa madre utilizo para elaborar un pan casero?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Entre un <\/span><b>15% y un 30%<\/b><span style=\"font-weight: 400;\"> del peso de la harina que vamos a utilizar. Por ejemplo, para un pan que lleve 540 gramos de harina usaremos unos 160 gr de masa madre, como en la siguiente receta: <\/span><a title=\"Receta de pan de masa madre\" href=\"https:\/\/www.conasi.eu\/blog\/recetas\/pan-de-masa-madre\/\"><span style=\"font-weight: 400;\">Pan de masa madre<\/span><\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFCuanta_agua_utilizo_para_elaborar_un_pan_El_porcentaje_de_hidratacion\"><\/span>\u00bfCu\u00e1nta agua utilizo para elaborar un pan? El porcentaje de hidrataci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Para no complicarnos demasiado, os aconsejamos al principio utilizar recetas ya calculadas que sepamos que funcionan.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">S<\/span><span style=\"font-weight: 400;\">i nos adentramos en el mundo del pan, llegar\u00e1 un punto en que querremos crear nosotros nuestras propias proporciones y encontrar un buen porcentaje de hidrataci\u00f3n, con el que nos sintamos c\u00f3modos <\/span><b>para elaborar panes a nuestro gusto.\u00a0<\/b><\/li>\n<li><b>Recomendamos comenzar por un 60-70%<\/b><span style=\"font-weight: 400;\"> de hidrataci\u00f3n en respecto a la cantidad de harina. Por ejemplo, para un pan de 1 kg de harina, usar\u00edamos unos 600-700 ml o g de agua, para un pan de 500 gr de harina, usar\u00edamos 300-350 ml o g de agua.<\/span><\/li>\n<li><b>Cuanto menos agua o menor porcentaje de hidrataci\u00f3n<\/b><span style=\"font-weight: 400;\">, m\u00e1s f\u00e1cil ser\u00e1 amasar. Quedar\u00e1 m\u00e1s compacto, con una corteza m\u00e1s gruesa y en general, menos aireado. <\/span><b>Ser\u00e1 una masa mucho m\u00e1s adecuada de trabajar para principiantes.<\/b><span style=\"font-weight: 400;\"> El porcentaje de hidrataci\u00f3n depender\u00e1 del tipo de pan que queramos elaborar, pero os recomendamos comenzar por porcentajes bajos.<\/span><\/li>\n<li><b>Cuanta m\u00e1s agua lleve la masa o mayor porcentaje de hidrataci\u00f3n,<\/b><span style=\"font-weight: 400;\"> el pan quedar\u00e1 <\/span><b>m\u00e1s aireado y ligero. <\/b><span style=\"font-weight: 400;\">Pero por otro lado, presentar\u00e1 m\u00e1s dificultades a la hora de amasar y requerir\u00e1 del empleo de t\u00e9cnicas de amasado m\u00e1s complejas con el fin de evitar que se desparrame la masa, c\u00f3mo por ejemplo, el amasado franc\u00e9s.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"La_autolisis\"><\/span>La autolisis<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><b>Un paso previo opcional,<\/b><span style=\"font-weight: 400;\"> que os recomendamos mucho antes del amasado definitivo, es la autolisis. Se trata de mezclar primero el agua junto con la harina, pero sin amasar y dejar reposar unos 30-120 minutos antes de a\u00f1adir el resto de ingredientes. La masa reposa y trabaja por s\u00ed sola, se rehidrata sin amasar y conlleva una serie de<\/span><b> ventajas:<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Reduce el tiempo de amasado posterior.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">A la hora de iniciar el amasado es m\u00e1s f\u00e1cil, no se pega tanto la masa.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Se oxida menos la masa.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para <\/span><b>elaborar la autolisis de forma casera<\/b><span style=\"font-weight: 400;\"> os proponemos 2 maneras:\u00a0<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">Mezclar <\/span><b>harina y agua<\/b><span style=\"font-weight: 400;\"> y dejar reposar desde 15 min a 2 horas, luego a\u00f1adir la masa madre y la sal y amasar.<\/span><\/li>\n<li><b>Mezclar la masa madre con el agua<\/b><span style=\"font-weight: 400;\"> hasta que se deshaga, luego incorporar la harina y dejar reposar un m\u00e1ximo de 30 min. A continuaci\u00f3n, a\u00f1adir la sal y proceder al amasado.<\/span><\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"La_humedad_de_la_masa\"><\/span>La humedad de la masa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Cuando comenzamos a amasar la masa del pan casero con masa madre <\/span><b>es normal que se sienta pegajosa<\/b><span style=\"font-weight: 400;\">, ello depender\u00e1 de la hidrataci\u00f3n y del tipo de pan que vayamos a elaborar.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">A medida que la vayamos amasando se ir\u00e1 integrando y secando, pero <\/span><b>siempre ser\u00e1 una masa m\u00e1s h\u00fameda que las masas con levadura a\u00f1adida.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Es preferible que <\/span><b>tienda a una consistencia m\u00e1s pegajosa<\/b><span style=\"font-weight: 400;\"> que no a una consistencia demasiado seca.\u00a0<\/span><\/li>\n<li><b>Dejar la masa ligeramente pegajosa y con la menor cantidad posible de harina<\/b><span style=\"font-weight: 400;\"> favorecer\u00e1 que el pan quede m\u00e1s ligero y con alveolos m\u00e1s grandes.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Una masa de pan que cueste mucho de trabajar y que resulte seca y dura al tacto tender\u00e1 a quedar m\u00e1s compacta y apelmazada.<\/span><\/li>\n<li><b>Demasiado seca:<\/b><span style=\"font-weight: 400;\"> si la masa se nota seca durante el amasado, nos podemos humedecer las manos para aportarle humedad.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFComo_saber_el_punto_correcto_de_amasado_de_la_masa\"><\/span>\u00bfC\u00f3mo saber el punto correcto de amasado de la masa?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">El tema del amasado no lo vamos a desarrollar en este post ya que consideramos que es extenso y hay muchas t\u00e9cnicas y formas de hacerlo. De todas formas, os aseguramos que aunque no tengamos una t\u00e9cnica de amasado, amasando el pan de forma intuitiva tambi\u00e9n podemos conseguir panes muy dignos y ricos.\u00a0<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Caracteristicas_de_una_masa_bien_amasada\"><\/span>Caracter\u00edsticas de una masa bien amasada<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Es suave y sedosa al tacto.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Es redondeada por los bordes tras el reposo.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Tiene cuerpo, estructura. En este punto hay que doblarla unas cuantas veces para generar tensi\u00f3n.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Cuando la estiramos de los extremos aguanta bien la extensi\u00f3n sin romperse f\u00e1cilmente. Deja pasar la luz, pero no se rompe.<\/span><\/li>\n<\/ul>\n<figure id=\"attachment_74395\" class=\"thumbnail wp-caption alignnone\" style=\"width: 910px\"><img decoding=\"async\" class=\"wp-image-74395 size-large\" title=\"Masa de pan en un cuenco - Pan casero con masa madre\" src=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-11-1-900x600.jpg\" alt=\"Masa de pan en un cuenco - Pan casero con masa madre\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-11-1.jpg 900w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-11-1-500x333.jpg 500w, https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-11-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"caption wp-caption-text\">Al presionar la masa con el dedo podemos comprobar si ha fermentado correctamente.<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"La_fermentacion_de_la_masa\"><\/span>La fermentaci\u00f3n de la masa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><b>Una vez amasada, la masa puede dejarse fermentar una media de entre 4 y 24 h:<\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">A mayor tiempo de fermentaci\u00f3n mayor acidez del pan.<\/span><\/li>\n<li><b>Se puede realizar la fermentaci\u00f3n m\u00e1s larga en la nevera<\/b><span style=\"font-weight: 400;\">, tras haber dejado que el pan leve unas horas previamente. Esto nos ser\u00e1 de utilidad cuando no podemos estar tan pendientes de \u00e9l. Tras unas 10-24 h en la nevera, lo sacamos y le volveremos a dar forma y tensi\u00f3n y dejaremos leudar de nuevo.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si <\/span><b>fermentamos demasiado la masa, esta colapsa y vuelve a bajar.<\/b><span style=\"font-weight: 400;\"> En este punto, podemos volverla amasar y dejarla levar de nuevo menos tiempo.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">A <\/span><b>menor tiempo de fermentaci\u00f3n<\/b><span style=\"font-weight: 400;\"> el pan quedar\u00e1 menos agrio\/\u00e1cido.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si utilizamos <\/span><b>harinas con mayor contenido en gluten la masa aguantar\u00e1 fermentaciones m\u00e1s largas.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Si utilizamos <\/span><b>harinas pobres o sin gluten,<\/b><span style=\"font-weight: 400;\"> tendremos que vigilar m\u00e1s el punto correcto de fermentaci\u00f3n. Estas no soportan bien las fermentaciones largas y es m\u00e1s f\u00e1cil que<\/span><b> la masa sobrefermente y aguante menos el leudado, ya que tiene menos fuerza.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Si estamos realizando una masa con un alto porcentaje de hidrataci\u00f3n, la cual se desperdiga f\u00e1cilmente, <\/span><b>nos ser\u00e1 de gran utilidad ayudarnos de un banneton o recipiente muy bien enharinado, para darle consistencia y forma<\/b><span style=\"font-weight: 400;\"> en el \u00faltimo leudado.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"El_punto_correcto_de_horneado\"><\/span>El punto correcto de horneado<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Para saber que <\/span><b>la masa est\u00e1 en su punto y ya ha fermentado suficiente<\/b><span style=\"font-weight: 400;\">, observaremos cierta tensi\u00f3n en la superficie, fineza, redondez y con cierta fuerza.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La masa debe haber formado una c\u00fapula redondeada.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La masa ya no crece m\u00e1s.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Al presionar con el dedo, \u00e9ste dejar\u00e1 huella y la masa recuperar\u00e1 su forma lentamente.<\/span><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Indicadores_de_que_la_masa_no_esta_en_el_punto_correcto\"><\/span>Indicadores de que la masa no est\u00e1 en el punto correcto<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Si al presionar con el dedo<\/span><b> la masa vuelve muy r\u00e1pidamente a su lugar sin dejar huella<\/b><span style=\"font-weight: 400;\"> es que le falta fermentaci\u00f3n, pero es buena se\u00f1al de que el proceso est\u00e1 en su cauce.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si al presionar con el dedo la masa no vuelve nunca a su lugar y queda la huella marcada significa que e<\/span><b>l pan ha fermentado demasiado,<\/b><span style=\"font-weight: 400;\"> ello puede ocurrir por varias razones:<\/span>\n<ul>\n<li><span style=\"font-weight: 400;\">Que la masa madre no estuviese lo suficientemente activa.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Que la hidrataci\u00f3n del pan no fuese la adecuada.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Que se haya dado forma al pan una vez ya sobrefermentada la masa.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Que lo hayamos dejado demasiado tiempo fermentando a temperatura ambiente.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u00bfEn tal caso qu\u00e9 podemos hacer? Una vez ha sobrefermentado la masa la podemos usar como prefermento, es decir como fermento para elaborar otro pan a\u00f1adiendo m\u00e1s harina, agua y un poquito de sal, volviendo a amasar y dejando fermentar de nuevo.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tipo de harina, temperatura del agua, cu\u00e1ndo refrescar la masa madre, saber cu\u00e1ndo est\u00e1 lista la masa para hornear y muchas m\u00e1s indicaciones para un pan con masa madre perfecto. <\/p>\n","protected":false},"author":2250,"featured_media":74392,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","wpupg_custom_link":[],"wpupg_custom_link_behaviour":["default"],"wpupg_custom_link_nofollow":[],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[652,2279,2298],"tags":[],"series":[],"class_list":{"0":"post-74357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-consejos-de-salud-consejos-de-salud","8":"category-macrobiotica","9":"category-macrobiotica-aida-lirola"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pan casero con masa madre: todos los trucos - Blog Conasi<\/title>\n<meta name=\"description\" content=\"Prescinde de comprar levaduras para un pan casero con masa madre: qu\u00e9 harina utilizar, c\u00f3mo fermentar y refrescar la masa madre, cu\u00e1l es su punto \u00f3ptimo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pan casero con masa madre: todos los trucos - Blog Conasi\" \/>\n<meta property=\"og:description\" content=\"Prescinde de comprar levaduras para un pan casero con masa madre: qu\u00e9 harina utilizar, c\u00f3mo fermentar y refrescar la masa madre, cu\u00e1l es su punto \u00f3ptimo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Conasi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/conasi\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T11:11:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T06:15:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A\u00efda Lirola - CONASI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conasicocina\" \/>\n<meta name=\"twitter:site\" content=\"@conasicocina\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"A\u00efda Lirola - CONASI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pan casero con masa madre: todos los trucos - Blog Conasi","description":"Prescinde de comprar levaduras para un pan casero con masa madre: qu\u00e9 harina utilizar, c\u00f3mo fermentar y refrescar la masa madre, cu\u00e1l es su punto \u00f3ptimo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/","og_locale":"es_ES","og_type":"article","og_title":"Pan casero con masa madre: todos los trucos - Blog Conasi","og_description":"Prescinde de comprar levaduras para un pan casero con masa madre: qu\u00e9 harina utilizar, c\u00f3mo fermentar y refrescar la masa madre, cu\u00e1l es su punto \u00f3ptimo.","og_url":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/","og_site_name":"Blog Conasi","article_publisher":"https:\/\/www.facebook.com\/conasi","article_published_time":"2020-04-27T11:11:48+00:00","article_modified_time":"2022-09-27T06:15:29+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg","type":"image\/jpeg"}],"author":"A\u00efda Lirola - CONASI","twitter_card":"summary_large_image","twitter_creator":"@conasicocina","twitter_site":"@conasicocina","twitter_misc":{"Escrito por":"A\u00efda Lirola - CONASI","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#article","isPartOf":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/"},"author":{"name":"A\u00efda Lirola - CONASI","@id":"https:\/\/www.conasi.eu\/blog\/#\/schema\/person\/96878abb9111b8838a9b2c8dadc71570"},"headline":"Pan casero con masa madre: trucos y consejos","datePublished":"2020-04-27T11:11:48+00:00","dateModified":"2022-09-27T06:15:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/"},"wordCount":3686,"commentCount":24,"image":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg","articleSection":["Consejos de salud","Macrobi\u00f3tica","Macrobi\u00f3tica: A\u00efda Lirola"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/","url":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/","name":"Pan casero con masa madre: todos los trucos - Blog Conasi","isPartOf":{"@id":"https:\/\/www.conasi.eu\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#primaryimage"},"image":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg","datePublished":"2020-04-27T11:11:48+00:00","dateModified":"2022-09-27T06:15:29+00:00","author":{"@id":"https:\/\/www.conasi.eu\/blog\/#\/schema\/person\/96878abb9111b8838a9b2c8dadc71570"},"description":"Prescinde de comprar levaduras para un pan casero con masa madre: qu\u00e9 harina utilizar, c\u00f3mo fermentar y refrescar la masa madre, cu\u00e1l es su punto \u00f3ptimo.","breadcrumb":{"@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#primaryimage","url":"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg","contentUrl":"https:\/\/www.conasi.eu\/blog\/wp-content\/uploads\/2020\/04\/pan-con-masa-madre-1.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.conasi.eu\/blog\/colaboradores-especiales\/macrobiotica-aida-lirola\/pan-casero-masa-madre-trucos-consejos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"El blog de Conasi","item":"https:\/\/www.conasi.eu\/blog\/"},{"@type":"ListItem","position":2,"name":"Colaboradores especiales","item":"https:\/\/www.conasi.eu\/blog\/secciones\/colaboradores-especiales\/"},{"@type":"ListItem","position":3,"name":"Macrobi\u00f3tica: A\u00efda Lirola","item":"https:\/\/www.conasi.eu\/blog\/secciones\/colaboradores-especiales\/macrobiotica-aida-lirola\/"},{"@type":"ListItem","position":4,"name":"Pan casero con masa madre: trucos y consejos"}]},{"@type":"WebSite","@id":"https:\/\/www.conasi.eu\/blog\/#website","url":"https:\/\/www.conasi.eu\/blog\/","name":"Blog Conasi","description":"Vive la cocina natural y libre de t\u00f3xicos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conasi.eu\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.conasi.eu\/blog\/#\/schema\/person\/96878abb9111b8838a9b2c8dadc71570","name":"A\u00efda Lirola - CONASI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.conasi.eu\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b1b7feb1018a70fa2a7cb7cd219e47e6f295a456facc4c6095d7f91a8044c8a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1b7feb1018a70fa2a7cb7cd219e47e6f295a456facc4c6095d7f91a8044c8a3?s=96&d=mm&r=g","caption":"A\u00efda Lirola - CONASI"},"description":"Natur\u00f3pata, especializada en cocina saludable. Formada en diet\u00e9tica y nutrici\u00f3n, macrobi\u00f3tica, diet\u00e9tica china y tradiciones culinarias. Focalizada en los \u00faltimos a\u00f1os en la fermentaci\u00f3n y la agricultura ecol\u00f3gica. Complementa su vocaci\u00f3n y profesi\u00f3n con el estudio y aplicaci\u00f3n de la aromaterapia y el ayuno como herramienta de salud. Desde el a\u00f1o 2016, comparte camino, pasi\u00f3n y aprendizaje en conasi como asesora, adem\u00e1s de elaborar contenidos y realizar demostraciones de cocina saludable.","sameAs":["https:\/\/www.conasi.eu\/blog\/secciones\/colaboradores-especiales\/macrobiotica-aida-lirola\/"],"url":"https:\/\/www.conasi.eu\/blog\/author\/aida-lirola\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/posts\/74357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/users\/2250"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/comments?post=74357"}],"version-history":[{"count":0,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/posts\/74357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/media\/74392"}],"wp:attachment":[{"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/media?parent=74357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/categories?post=74357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/tags?post=74357"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/www.conasi.eu\/blog\/wp-json\/wp\/v2\/series?post=74357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}